{"id":30520,"count":1,"description":"","link":"https:\/\/boardgeneration.ch\/en\/tag\/deeluxe\/","name":"Deeluxe","slug":"deeluxe","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deeluxe Archive - Board Generation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boardgeneration.ch\/en\/tag\/deeluxe\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deeluxe Archive - Board Generation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boardgeneration.ch\/en\/tag\/deeluxe\/\" \/>\n<meta property=\"og:site_name\" content=\"Board Generation\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@boardgen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/boardgeneration.ch\/en\/tag\/deeluxe\/\",\"url\":\"https:\/\/boardgeneration.ch\/en\/tag\/deeluxe\/\",\"name\":\"Deeluxe Archive - Board Generation\",\"isPartOf\":{\"@id\":\"https:\/\/boardgeneration.ch\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/boardgeneration.ch\/en\/tag\/deeluxe\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/boardgeneration.ch\/en\/tag\/deeluxe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/boardgeneration.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deeluxe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/boardgeneration.ch\/#website\",\"url\":\"https:\/\/boardgeneration.ch\/\",\"name\":\"board generation\",\"description\":\"Back to the Roots\",\"publisher\":{\"@id\":\"https:\/\/boardgeneration.ch\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/boardgeneration.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/boardgeneration.ch\/#organization\",\"name\":\"board generation\",\"url\":\"https:\/\/boardgeneration.ch\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/boardgeneration.ch\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/boardgeneration.ch\/wp-content\/uploads\/2019\/01\/bg-logo_mit_Text.png\",\"contentUrl\":\"https:\/\/boardgeneration.ch\/wp-content\/uploads\/2019\/01\/bg-logo_mit_Text.png\",\"width\":1040,\"height\":1155,\"caption\":\"board generation\"},\"image\":{\"@id\":\"https:\/\/boardgeneration.ch\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/boardgeneration.ch\",\"https:\/\/x.com\/boardgen\",\"https:\/\/www.instagram.com\/boardgen\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deeluxe Archive - Board Generation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boardgeneration.ch\/en\/tag\/deeluxe\/","og_locale":"en_GB","og_type":"article","og_title":"Deeluxe Archive - Board Generation","og_url":"https:\/\/boardgeneration.ch\/en\/tag\/deeluxe\/","og_site_name":"Board Generation","twitter_card":"summary_large_image","twitter_site":"@boardgen","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/boardgeneration.ch\/en\/tag\/deeluxe\/","url":"https:\/\/boardgeneration.ch\/en\/tag\/deeluxe\/","name":"Deeluxe Archive - Board Generation","isPartOf":{"@id":"https:\/\/boardgeneration.ch\/#website"},"breadcrumb":{"@id":"https:\/\/boardgeneration.ch\/en\/tag\/deeluxe\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/boardgeneration.ch\/en\/tag\/deeluxe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/boardgeneration.ch\/"},{"@type":"ListItem","position":2,"name":"Deeluxe"}]},{"@type":"WebSite","@id":"https:\/\/boardgeneration.ch\/#website","url":"https:\/\/boardgeneration.ch\/","name":"board generation","description":"Back to the Roots","publisher":{"@id":"https:\/\/boardgeneration.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boardgeneration.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/boardgeneration.ch\/#organization","name":"board generation","url":"https:\/\/boardgeneration.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/boardgeneration.ch\/#\/schema\/logo\/image\/","url":"https:\/\/boardgeneration.ch\/wp-content\/uploads\/2019\/01\/bg-logo_mit_Text.png","contentUrl":"https:\/\/boardgeneration.ch\/wp-content\/uploads\/2019\/01\/bg-logo_mit_Text.png","width":1040,"height":1155,"caption":"board generation"},"image":{"@id":"https:\/\/boardgeneration.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/boardgeneration.ch","https:\/\/x.com\/boardgen","https:\/\/www.instagram.com\/boardgen\/"]}]}},"_links":{"self":[{"href":"https:\/\/boardgeneration.ch\/en\/wp-json\/wp\/v2\/tags\/30520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boardgeneration.ch\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/boardgeneration.ch\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/boardgeneration.ch\/en\/wp-json\/wp\/v2\/posts?tags=30520"},{"href":"https:\/\/boardgeneration.ch\/en\/wp-json\/wp\/v2\/ajde_events?tags=30520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}