{"id":40327,"count":1,"description":"","link":"https:\/\/boardgeneration.ch\/fr\/tag\/the-natural-selection-tour\/","name":"La tourn\u00e9e de la s\u00e9lection naturelle","slug":"the-natural-selection-tour","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Natural Selection Tour Archive - Board Generation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boardgeneration.ch\/fr\/tag\/the-natural-selection-tour\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Natural Selection Tour Archive - Board Generation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boardgeneration.ch\/fr\/tag\/the-natural-selection-tour\/\" \/>\n<meta property=\"og:site_name\" content=\"Board Generation\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@boardgen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/boardgeneration.ch\/en\/tag\/the-natural-selection-tour\/\",\"url\":\"https:\/\/boardgeneration.ch\/en\/tag\/the-natural-selection-tour\/\",\"name\":\"The Natural Selection Tour Archive - Board Generation\",\"isPartOf\":{\"@id\":\"https:\/\/boardgeneration.ch\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/boardgeneration.ch\/en\/tag\/the-natural-selection-tour\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/boardgeneration.ch\/en\/tag\/the-natural-selection-tour\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/boardgeneration.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Natural Selection Tour\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/boardgeneration.ch\/#website\",\"url\":\"https:\/\/boardgeneration.ch\/\",\"name\":\"board generation\",\"description\":\"Back to the Roots\",\"publisher\":{\"@id\":\"https:\/\/boardgeneration.ch\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/boardgeneration.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/boardgeneration.ch\/#organization\",\"name\":\"board generation\",\"url\":\"https:\/\/boardgeneration.ch\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/boardgeneration.ch\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/boardgeneration.ch\/wp-content\/uploads\/2019\/01\/bg-logo_mit_Text.png\",\"contentUrl\":\"https:\/\/boardgeneration.ch\/wp-content\/uploads\/2019\/01\/bg-logo_mit_Text.png\",\"width\":1040,\"height\":1155,\"caption\":\"board generation\"},\"image\":{\"@id\":\"https:\/\/boardgeneration.ch\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/boardgeneration.ch\",\"https:\/\/x.com\/boardgen\",\"https:\/\/www.instagram.com\/boardgen\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Natural Selection Tour Archive - Board Generation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boardgeneration.ch\/fr\/tag\/the-natural-selection-tour\/","og_locale":"fr_FR","og_type":"article","og_title":"The Natural Selection Tour Archive - Board Generation","og_url":"https:\/\/boardgeneration.ch\/fr\/tag\/the-natural-selection-tour\/","og_site_name":"Board Generation","twitter_card":"summary_large_image","twitter_site":"@boardgen","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/boardgeneration.ch\/en\/tag\/the-natural-selection-tour\/","url":"https:\/\/boardgeneration.ch\/en\/tag\/the-natural-selection-tour\/","name":"The Natural Selection Tour Archive - Board Generation","isPartOf":{"@id":"https:\/\/boardgeneration.ch\/#website"},"breadcrumb":{"@id":"https:\/\/boardgeneration.ch\/en\/tag\/the-natural-selection-tour\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/boardgeneration.ch\/en\/tag\/the-natural-selection-tour\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/boardgeneration.ch\/"},{"@type":"ListItem","position":2,"name":"The Natural Selection Tour"}]},{"@type":"WebSite","@id":"https:\/\/boardgeneration.ch\/#website","url":"https:\/\/boardgeneration.ch\/","name":"g\u00e9n\u00e9ration de conseils","description":"Retour aux sources","publisher":{"@id":"https:\/\/boardgeneration.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boardgeneration.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/boardgeneration.ch\/#organization","name":"g\u00e9n\u00e9ration de conseils","url":"https:\/\/boardgeneration.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/boardgeneration.ch\/#\/schema\/logo\/image\/","url":"https:\/\/boardgeneration.ch\/wp-content\/uploads\/2019\/01\/bg-logo_mit_Text.png","contentUrl":"https:\/\/boardgeneration.ch\/wp-content\/uploads\/2019\/01\/bg-logo_mit_Text.png","width":1040,"height":1155,"caption":"board generation"},"image":{"@id":"https:\/\/boardgeneration.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/boardgeneration.ch","https:\/\/x.com\/boardgen","https:\/\/www.instagram.com\/boardgen\/"]}]}},"_links":{"self":[{"href":"https:\/\/boardgeneration.ch\/fr\/wp-json\/wp\/v2\/tags\/40327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boardgeneration.ch\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/boardgeneration.ch\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/boardgeneration.ch\/fr\/wp-json\/wp\/v2\/posts?tags=40327"},{"href":"https:\/\/boardgeneration.ch\/fr\/wp-json\/wp\/v2\/ajde_events?tags=40327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}